{"id":16461,"date":"2026-07-06T17:12:37","date_gmt":"2026-07-06T15:12:37","guid":{"rendered":"https:\/\/www.denatuurlijkekappershop.nl\/?post_type=product&#038;p=16461"},"modified":"2026-07-06T17:17:24","modified_gmt":"2026-07-06T15:17:24","slug":"green-heads-leave-in-balm-150-ml","status":"publish","type":"product","link":"https:\/\/www.denatuurlijkekappershop.nl\/pt\/green-heads-leave-in-balm-150ml\/","title":{"rendered":"B\u00e1lsamo sem enxaguamento Green Heads 150 ml"},"content":{"rendered":"<p>O GREEN HEADS Leave-in Balm \u00e9 um condicionador sem enxaguamento nutritivo para cabelos que precisam de hidrata\u00e7\u00e3o, suavidade e elasticidade adicionais. A sua f\u00f3rmula leve ajuda a facilitar a pentea\u00e7\u00e3o, reduz o frizz e confere um brilho natural sem deixar o cabelo pesado ou oleoso.<\/p>\n<p>Este b\u00e1lsamo sem enxaguamento \u00e9 ideal para cabelos normais a secos, cabelos que se emaranham facilmente ou cabelos que precisam de um cuidado extra ap\u00f3s a lavagem. A f\u00f3rmula cont\u00e9m, entre outros ingredientes, alo\u00e9 vera, \u00f3leo de br\u00f3colos e \u00f3leo de Abiss\u00ednia. A alo\u00e9 vera ajuda a hidratar o cabelo, o \u00f3leo de br\u00f3colos contribui para o brilho e facilita o desembara\u00e7amento, e o \u00f3leo de Abiss\u00ednia confere ao cabelo uma sensa\u00e7\u00e3o de suavidade e maciez.<\/p>\n<p>O b\u00e1lsamo tamb\u00e9m funciona muito bem como primer antes de secar o cabelo com o secador ou de o modelar. O cabelo fica mais macio ao toque e adquire um acabamento cuidado e liso. Tamb\u00e9m se pode utilizar uma pequena quantidade no cabelo seco para proporcionar hidrata\u00e7\u00e3o extra, real\u00e7ar carac\u00f3is leves ou reduzir o frizz.<\/p>\n<p>O aroma \u00e9 fresco e subtil, com uma sensa\u00e7\u00e3o olfativa de Lemon Spritzer.<\/p>","protected":false},"excerpt":{"rendered":"<p>Condicionador hidratante sem enxaguamento para cabelos normais a secos. Desembara\u00e7a, reduz o frizz e confere suavidade e brilho ao cabelo sem o deixar pesado.<\/p>","protected":false},"featured_media":16462,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[683],"product_cat":[415,682,198,430],"product_tag":[560,562],"class_list":["post-16461","product","type-product","status-publish","has-post-thumbnail","product_brand-green-heads","product_cat-haarverzorging","product_cat-green-heads","product_cat-merken","product_cat-styling","product_tag-anti-roos","product_tag-gevoeligehoofdhuid","pa_certificering-100-vegan","pa_certificering-animal-test-free","pa_geschikt-voor-dik-haar","pa_geschikt-voor-droog-haar","pa_geschikt-voor-fijn-dun-haar","pa_geschikt-voor-kort-haar","pa_geschikt-voor-krullen","pa_geschikt-voor-pluizig-haar","pa_inhoud-150ml","pa_merk-green-heads","pa_soort-product-haarverzorging","pa_soort-product-styling","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"composite_virtual":false,"composite_layout":"","composite_add_to_cart_form_location":"","composite_editable_in_cart":false,"composite_sold_individually_context":"","composite_shop_price_calc":"","composite_components":[],"composite_scenarios":[],"exclude_global_add_ons":[],"addons":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.denatuurlijkekappershop.nl\/pt\/wp-json\/wp\/v2\/product\/16461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.denatuurlijkekappershop.nl\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.denatuurlijkekappershop.nl\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.denatuurlijkekappershop.nl\/pt\/wp-json\/wp\/v2\/comments?post=16461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.denatuurlijkekappershop.nl\/pt\/wp-json\/wp\/v2\/media\/16462"}],"wp:attachment":[{"href":"https:\/\/www.denatuurlijkekappershop.nl\/pt\/wp-json\/wp\/v2\/media?parent=16461"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.denatuurlijkekappershop.nl\/pt\/wp-json\/wp\/v2\/product_brand?post=16461"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.denatuurlijkekappershop.nl\/pt\/wp-json\/wp\/v2\/product_cat?post=16461"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.denatuurlijkekappershop.nl\/pt\/wp-json\/wp\/v2\/product_tag?post=16461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}